{"id":4778,"date":"2025-09-18T09:58:02","date_gmt":"2025-09-18T07:58:02","guid":{"rendered":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/?post_type=property&#038;p=4778"},"modified":"2025-09-18T09:58:02","modified_gmt":"2025-09-18T07:58:02","slug":"1-a-lage-gewerbeflaeche-an-der-kaiserstr-lienhardplatz-in-w-vohwinkel","status":"publish","type":"property","link":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/immobilie\/1-a-lage-gewerbeflaeche-an-der-kaiserstr-lienhardplatz-in-w-vohwinkel\/","title":{"rendered":"1-A LAGE! GEWERBEFL\u00c4CHE AN DER KAISERSTR.\/LIENHARDPLATZ IN W-VOHWINKEL!"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\"><strong>OBJEKTBESCHREIBUNG<\/strong><\/p>\n<p>Der Laden befindet sich in einem sehr gepflegtem Wohn- Gesch\u00e4ftshaus, 1-A Lage an der Lienhardtstr.\/Kaiserstr.<\/p>\n<p>Einen genaueren Eindruck k\u00f6nnen Sie sich gerne bei einem pers\u00f6nlichen Besichtigungstermin beschaffen.<\/p>\n<p><strong>AUSSTATTUNG<\/strong><\/p>\n<ul>\n<li>gro\u00dfe Schaufenster<\/li>\n<li>Fliesenboden- Laminatboden<\/li>\n<li>WC<\/li>\n<li>2 x R\u00e4ume mit Zugang auf die gro\u00dfe Terrasse im Hof<\/li>\n<li>K\u00fcchenecke<\/li>\n<li>Deckenbeleuchtung<\/li>\n<li>renovierter Zustand<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>LAGE<\/strong><\/p>\n<p>Zentrale Gesch\u00e4ftslage in Wuppertal-Vohwinkel, mit sehr guter Anbindung an die \u00f6ffentlichen Verkehrsmittel. Optimale Gesch\u00e4ftslage.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Besichtigungstermine<\/strong><\/p>\n<p>Besichtigungstermine bei schriftlicher Kontaktanfrage \u00fcber das Immobilienportal.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sonstiges<\/strong><\/p>\n<p>KAUTION: 3 x Monatskaltmieten<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PROVISION F\u00dcR MIETER<\/strong><\/p>\n<p>2,5 Makler-Honorar vom Mieter zzgl. 19% gesetzlicher MwSt.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OBJEKTBESCHREIBUNG Der Laden befindet sich in einem sehr gepflegtem Wohn- Gesch\u00e4ftshaus, 1-A Lage an der Lienhardtstr.\/Kaiserstr. Einen genaueren Eindruck k\u00f6nnen Sie sich gerne bei einem pers\u00f6nlichen Besichtigungstermin beschaffen. AUSSTATTUNG gro\u00dfe Schaufenster Fliesenboden- Laminatboden WC 2 x R\u00e4ume mit Zugang auf die gro\u00dfe Terrasse im Hof K\u00fcchenecke Deckenbeleuchtung renovierter Zustand &nbsp; LAGE Zentrale Gesch\u00e4ftslage in Wuppertal-Vohwinkel,<\/p>\n","protected":false},"author":4,"featured_media":4780,"template":"","meta":{"footnotes":""},"offertype":[64],"proptype":[104],"location":[77],"rooms":[86],"size":[90],"price":[],"keyword":[],"class_list":["post-4778","property","type-property","status-publish","has-post-thumbnail","hentry","offertype-vermietung","proptype-gewerbeimmobilie-zur-miete","location-wuppertal","rooms-3-4","size-50-bis-100qm"],"_links":{"self":[{"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/property\/4778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/property\/4778\/revisions"}],"predecessor-version":[{"id":4779,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/property\/4778\/revisions\/4779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/media\/4780"}],"wp:attachment":[{"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/media?parent=4778"}],"wp:term":[{"taxonomy":"offertype","embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/offertype?post=4778"},{"taxonomy":"proptype","embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/proptype?post=4778"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/location?post=4778"},{"taxonomy":"rooms","embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/rooms?post=4778"},{"taxonomy":"size","embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/size?post=4778"},{"taxonomy":"price","embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/price?post=4778"},{"taxonomy":"keyword","embeddable":true,"href":"https:\/\/www.wuppertal-immobilien.info\/immobilien-angebote\/wp-json\/wp\/v2\/keyword?post=4778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}